{"id":8377,"date":"2021-05-06T11:21:09","date_gmt":"2021-05-06T09:21:09","guid":{"rendered":"https:\/\/vipgo.atsautomation.com\/comacitalia\/linee-di-imbottigliamento\/"},"modified":"2021-12-20T11:06:41","modified_gmt":"2021-12-20T10:06:41","slug":"abfuelllinien-fuer-flaschen","status":"publish","type":"page","link":"https:\/\/vipgo.atsautomation.com\/de\/abfuelllinien-fuer-flaschen\/","title":{"rendered":"Abf\u00fclllinien f\u00fcr Flaschen"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1637662557597{margin-bottom: 0px !important;}&#8220;]Automatische Flaschenabf\u00fcllsysteme zur Verarbeitung und Abf\u00fcllung von Getr\u00e4nken in Flaschen jeder Gr\u00f6\u00dfe. Die Abf\u00fclllinien werden entsprechend den technischen Anforderungen der Kunden konfektioniert, denen dazu die besten verf\u00fcgbaren L\u00f6sungen aus dem breiten Spektrum von Comac entwickelter Maschinen zur Auswahl gestellt werden.<\/p>\n<p>Comac r\u00fcstet Unternehmen in aller Welt mit Flaschenabf\u00fcllanlagen und Maschinen jeder Art und Gr\u00f6\u00dfe aus. Dabei werden f\u00fcr jedes abzuf\u00fcllende Produkt kundenspezifische L\u00f6sungen entwickelt.<\/p>\n<p>Unsere Anlagen sind vollautomatisch und wir haben drei Kategorien im Angebot:[\/vc_column_text][comac_read_more]Gli impianti, studiati per il trattamento di bottiglie standard in vetro, possono essere adattati anche per il trattamento di bottiglie con forme particolari.<\/p>\n<p>Le nostre linee di imbottigliamento possono processare:<\/p>\n<ul>\n<li>birra<\/li>\n<li>vino<\/li>\n<li>bevande alcoliche\/analcoliche<\/li>\n<li>acqua naturale o gassata<\/li>\n<\/ul>\n<p>La<strong>\u00a0competenza<\/strong>\u00a0tecnica, l\u2019<strong>alta tecnologia<\/strong>\u00a0e la\u00a0<strong>qualit\u00e0 delle materie prime<\/strong>\u00a0utilizzate garantiscono l\u2019affidabilit\u00e0 degli impianti e le rese ottimali.<\/p>\n<p>Gli impianti sono attuati per semplificare e velocizzare al massimo le operazioni di cambio formato.<\/p>\n<p>Gli impianti\u00a0<strong>fino e oltre 12.000 BPH<\/strong>\u00a0vetro sono prodotti e sviluppati in collaborazione con il\u00a0<strong>gruppo CFT<\/strong>.<\/p>\n<ul>\n<li>Flaschenabf\u00fcll-Linien mit einer Kapazit\u00e4t <strong>bis 6.000 Fph bei Glasflaschen<\/strong><\/li>\n<li>Flaschenabf\u00fcll-Linien mit einer Kapazit\u00e4t <strong>von mehr als 12.000 Fph bei Glasflaschen<\/strong><\/li>\n<li>Flaschenabf\u00fcll-Linien mit einer Kapazit\u00e4t <strong>bis 12.000 Fph bei Glasflaschen<\/strong><\/li>\n<\/ul>\n<p>Die Maschinen sind f\u00fcr die Verwendung von Standardglasflaschen designt, sie lassen sich jedoch auch f\u00fcr Flaschen mit speziellen Formen anpassen. Comacs zwanzigj\u00e4hrige technische Erfahrung sowie die hochentwickelte Technologie und Qualit\u00e4t der verwendeten Materialien gew\u00e4hrleisten zuverl\u00e4ssige Anlagen und optimale Ertr\u00e4ge.<\/p>\n<p>Die Ausr\u00fcstung der Abf\u00fcllanlagen ist so gestaltet, dass die Umstellung bei einem Produktwechsel schnell und simpel ist.[\/comac_read_more][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1637662557597{margin-bottom: 0px !important;}&#8220;]Automatische Flaschenabf\u00fcllsysteme zur Verarbeitung und Abf\u00fcllung von Getr\u00e4nken in Flaschen jeder Gr\u00f6\u00dfe. Die Abf\u00fclllinien werden entsprechend den technischen Anforderungen der Kunden konfektioniert, denen dazu die besten verf\u00fcgbaren L\u00f6sungen aus dem breiten Spektrum von Comac entwickelter Maschinen zur Auswahl gestellt werden. Comac r\u00fcstet Unternehmen in aller Welt mit Flaschenabf\u00fcllanlagen und Maschinen jeder Art [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8378,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-linee-bottiglie.php","meta":{"footnotes":""},"class_list":["post-8377","page","type-page","status-publish","has-post-thumbnail","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Abf\u00fclllinien f\u00fcr Flaschen - Comac<\/title>\n<meta name=\"description\" content=\"Comac offre impianti completi per la produzione, il processo ed il confezionamento di bevande in bottiglie in vetro. Scopri di pi\u00f9!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abf\u00fclllinien f\u00fcr Flaschen\" \/>\n<meta property=\"og:description\" content=\"Comac offre impianti completi per la produzione, il processo ed il confezionamento di bevande in bottiglie in vetro. Scopri di pi\u00f9!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/\" \/>\n<meta property=\"og:site_name\" content=\"Comac\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T10:06:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comacitalia.de\/wp-content\/uploads\/2021\/05\/linee-bottiglie-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/\",\"url\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/\",\"name\":\"Abf\u00fclllinien f\u00fcr Flaschen - Comac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linee-bottiglie-1.jpg\",\"datePublished\":\"2021-05-06T09:21:09+00:00\",\"dateModified\":\"2021-12-20T10:06:41+00:00\",\"description\":\"Comac offre impianti completi per la produzione, il processo ed il confezionamento di bevande in bottiglie in vetro. Scopri di pi\u00f9!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linee-bottiglie-1.jpg\",\"contentUrl\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linee-bottiglie-1.jpg\",\"width\":1920,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=en\\\/abfulllinien-fur-flaschen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abf\u00fclllinien f\u00fcr Flaschen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=it\\\/#website\",\"url\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=it\\\/\",\"name\":\"Comac\",\"description\":\"Kegging &amp; bottling plant\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vipgo.atsautomation.com\\\/?lang=it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Abf\u00fclllinien f\u00fcr Flaschen - Comac","description":"Comac offre impianti completi per la produzione, il processo ed il confezionamento di bevande in bottiglie in vetro. Scopri di pi\u00f9!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Abf\u00fclllinien f\u00fcr Flaschen","og_description":"Comac offre impianti completi per la produzione, il processo ed il confezionamento di bevande in bottiglie in vetro. Scopri di pi\u00f9!","og_url":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/","og_site_name":"Comac","article_modified_time":"2021-12-20T10:06:41+00:00","og_image":[{"width":1920,"height":272,"url":"https:\/\/www.comacitalia.de\/wp-content\/uploads\/2021\/05\/linee-bottiglie-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/","url":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/","name":"Abf\u00fclllinien f\u00fcr Flaschen - Comac","isPartOf":{"@id":"https:\/\/vipgo.atsautomation.com\/?lang=it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/#primaryimage"},"image":{"@id":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/#primaryimage"},"thumbnailUrl":"https:\/\/vipgo.atsautomation.com\/wp-content\/uploads\/2021\/05\/linee-bottiglie-1.jpg","datePublished":"2021-05-06T09:21:09+00:00","dateModified":"2021-12-20T10:06:41+00:00","description":"Comac offre impianti completi per la produzione, il processo ed il confezionamento di bevande in bottiglie in vetro. Scopri di pi\u00f9!","breadcrumb":{"@id":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/#primaryimage","url":"https:\/\/vipgo.atsautomation.com\/wp-content\/uploads\/2021\/05\/linee-bottiglie-1.jpg","contentUrl":"https:\/\/vipgo.atsautomation.com\/wp-content\/uploads\/2021\/05\/linee-bottiglie-1.jpg","width":1920,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/vipgo.atsautomation.com\/?lang=en\/abfulllinien-fur-flaschen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home"},{"@type":"ListItem","position":2,"name":"Abf\u00fclllinien f\u00fcr Flaschen"}]},{"@type":"WebSite","@id":"https:\/\/vipgo.atsautomation.com\/?lang=it\/#website","url":"https:\/\/vipgo.atsautomation.com\/?lang=it\/","name":"Comac","description":"Kegging &amp; bottling plant","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vipgo.atsautomation.com\/?lang=it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/pages\/8377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/comments?post=8377"}],"version-history":[{"count":3,"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/pages\/8377\/revisions"}],"predecessor-version":[{"id":8382,"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/pages\/8377\/revisions\/8382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/media\/8378"}],"wp:attachment":[{"href":"https:\/\/vipgo.atsautomation.com\/de\/wp-json\/wp\/v2\/media?parent=8377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}